{"id":27723,"date":"2026-05-13T18:13:58","date_gmt":"2026-05-13T16:13:58","guid":{"rendered":"https:\/\/thefamilyoffice.ch\/lart-video-et-numerique-le-futur-des-investissements-culturels-de\/"},"modified":"2026-05-13T18:13:58","modified_gmt":"2026-05-13T16:13:58","slug":"lart-video-et-numerique-le-futur-des-investissements-culturels-de","status":"publish","type":"post","link":"https:\/\/thefamilyoffice.ch\/de\/lart-video-et-numerique-le-futur-des-investissements-culturels-de\/","title":{"rendered":"Digitale und videok\u00fcnstlerische Medien: die Zukunft der kulturellen Invest\u001b[6D\u001b[K\nInvestitionen (German)"},"content":{"rendered":"<p>Traduction en cours (Deutsch)&#8230;<\/p>","protected":false},"excerpt":{"rendered":"<p>Traduction en cours (Deutsch)&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[],"class_list":["post-27723","post","type-post","status-publish","format-standard","hentry","category-unkategorisiert","category-37","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Digitale und videok\u00fcnstlerische Medien: die Zukunft der kulturellen Invest\u001b[6D\u001b[K Investitionen (German) - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse<\/title>\n<meta name=\"description\" content=\"Digitale und videok\u00fcnstlerische Medien: die Zukunft der kulturellen Invest\u001b[6D\u001b[K Investitionen (German) - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thefamilyoffice.ch\/de\/lart-video-et-numerique-le-futur-des-investissements-culturels-de\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Digitale und videok\u00fcnstlerische Medien: die Zukunft der kulturellen Invest\u001b[6D\u001b[K Investitionen (German) - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"twitter:description\" content=\"Digitale und videok\u00fcnstlerische Medien: die Zukunft der kulturellen Invest\u001b[6D\u001b[K Investitionen (German) - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"laurent\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/lart-video-et-numerique-le-futur-des-investissements-culturels-de\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/lart-video-et-numerique-le-futur-des-investissements-culturels-de\\\/\"},\"author\":{\"name\":\"laurent\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\"},\"headline\":\"Digitale und videok\u00fcnstlerische Medien: die Zukunft der kulturellen Invest\\u001b[6D\\u001b[K Investitionen (German)\",\"datePublished\":\"2026-05-13T16:13:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/lart-video-et-numerique-le-futur-des-investissements-culturels-de\\\/\"},\"wordCount\":18,\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/lart-video-et-numerique-le-futur-des-investissements-culturels-de\\\/\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/lart-video-et-numerique-le-futur-des-investissements-culturels-de\\\/\",\"name\":\"Digitale und videok\u00fcnstlerische Medien: die Zukunft der kulturellen Invest\\u001b[6D\\u001b[K Investitionen (German) - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/#website\"},\"datePublished\":\"2026-05-13T16:13:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\"},\"description\":\"Digitale und videok\u00fcnstlerische Medien: die Zukunft der kulturellen Invest\\u001b[6D\\u001b[K Investitionen (German) - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/lart-video-et-numerique-le-futur-des-investissements-culturels-de\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/lart-video-et-numerique-le-futur-des-investissements-culturels-de\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/lart-video-et-numerique-le-futur-des-investissements-culturels-de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Digitale und videok\u00fcnstlerische Medien: die Zukunft der kulturellen Invest\\u001b[6D\\u001b[K Investitionen (German)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/\",\"name\":\"The Family Office\",\"description\":\"The Family Office\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\",\"name\":\"laurent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"caption\":\"laurent\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Digitale und videok\u00fcnstlerische Medien: die Zukunft der kulturellen Invest\u001b[6D\u001b[K Investitionen (German) - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","description":"Digitale und videok\u00fcnstlerische Medien: die Zukunft der kulturellen Invest\u001b[6D\u001b[K Investitionen (German) - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thefamilyoffice.ch\/de\/lart-video-et-numerique-le-futur-des-investissements-culturels-de\/","twitter_card":"summary_large_image","twitter_title":"Digitale und videok\u00fcnstlerische Medien: die Zukunft der kulturellen Invest\u001b[6D\u001b[K Investitionen (German) - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","twitter_description":"Digitale und videok\u00fcnstlerische Medien: die Zukunft der kulturellen Invest\u001b[6D\u001b[K Investitionen (German) - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","twitter_misc":{"Verfasst von":"laurent"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thefamilyoffice.ch\/de\/lart-video-et-numerique-le-futur-des-investissements-culturels-de\/#article","isPartOf":{"@id":"https:\/\/thefamilyoffice.ch\/de\/lart-video-et-numerique-le-futur-des-investissements-culturels-de\/"},"author":{"name":"laurent","@id":"https:\/\/thefamilyoffice.ch\/de\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee"},"headline":"Digitale und videok\u00fcnstlerische Medien: die Zukunft der kulturellen Invest\u001b[6D\u001b[K Investitionen (German)","datePublished":"2026-05-13T16:13:58+00:00","mainEntityOfPage":{"@id":"https:\/\/thefamilyoffice.ch\/de\/lart-video-et-numerique-le-futur-des-investissements-culturels-de\/"},"wordCount":18,"articleSection":["Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/thefamilyoffice.ch\/de\/lart-video-et-numerique-le-futur-des-investissements-culturels-de\/","url":"https:\/\/thefamilyoffice.ch\/de\/lart-video-et-numerique-le-futur-des-investissements-culturels-de\/","name":"Digitale und videok\u00fcnstlerische Medien: die Zukunft der kulturellen Invest\u001b[6D\u001b[K Investitionen (German) - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","isPartOf":{"@id":"https:\/\/thefamilyoffice.ch\/de\/#website"},"datePublished":"2026-05-13T16:13:58+00:00","author":{"@id":"https:\/\/thefamilyoffice.ch\/de\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee"},"description":"Digitale und videok\u00fcnstlerische Medien: die Zukunft der kulturellen Invest\u001b[6D\u001b[K Investitionen (German) - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","breadcrumb":{"@id":"https:\/\/thefamilyoffice.ch\/de\/lart-video-et-numerique-le-futur-des-investissements-culturels-de\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thefamilyoffice.ch\/de\/lart-video-et-numerique-le-futur-des-investissements-culturels-de\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/thefamilyoffice.ch\/de\/lart-video-et-numerique-le-futur-des-investissements-culturels-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/thefamilyoffice.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Digitale und videok\u00fcnstlerische Medien: die Zukunft der kulturellen Invest\u001b[6D\u001b[K Investitionen (German)"}]},{"@type":"WebSite","@id":"https:\/\/thefamilyoffice.ch\/de\/#website","url":"https:\/\/thefamilyoffice.ch\/de\/","name":"The Family Office","description":"The Family Office","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thefamilyoffice.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/thefamilyoffice.ch\/de\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee","name":"laurent","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","caption":"laurent"}}]}},"_links":{"self":[{"href":"https:\/\/thefamilyoffice.ch\/de\/wp-json\/wp\/v2\/posts\/27723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thefamilyoffice.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thefamilyoffice.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/de\/wp-json\/wp\/v2\/comments?post=27723"}],"version-history":[{"count":0,"href":"https:\/\/thefamilyoffice.ch\/de\/wp-json\/wp\/v2\/posts\/27723\/revisions"}],"wp:attachment":[{"href":"https:\/\/thefamilyoffice.ch\/de\/wp-json\/wp\/v2\/media?parent=27723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/de\/wp-json\/wp\/v2\/categories?post=27723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/de\/wp-json\/wp\/v2\/tags?post=27723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}