{"id":27741,"date":"2026-05-13T18:15:36","date_gmt":"2026-05-13T16:15:36","guid":{"rendered":"https:\/\/thefamilyoffice.ch\/analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de\/"},"modified":"2026-05-13T18:15:36","modified_gmt":"2026-05-13T16:15:36","slug":"analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de","status":"publish","type":"post","link":"https:\/\/thefamilyoffice.ch\/de\/analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de\/","title":{"rendered":"Kettenanalyse zur Beziehung zwischen Herkunft und Wahrnehmung k\u00fcnstlerisch\u001b[12D\u001b[K\nk\u00fcnstlerischer Qualit\u00e4t\n\nPlease note that this is a machine-generated translation and may not be ful\u001b[3D\u001b[K\nfully acc"},"content":{"rendered":"<p>Traduction en cours (Deutsch)&#8230;<\/p>","protected":false},"excerpt":{"rendered":"<p>Traduction en cours (Deutsch)&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[],"class_list":["post-27741","post","type-post","status-publish","format-standard","hentry","category-unkategorisiert","category-37","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kettenanalyse zur Beziehung zwischen Herkunft und Wahrnehmung k\u00fcnstlerisch\u001b[12D\u001b[K k\u00fcnstlerischer Qualit\u00e4t Please note that this is a machine-generated translation and may not be ful\u001b[3D\u001b[K fully acc - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse<\/title>\n<meta name=\"description\" content=\"Kettenanalyse zur Beziehung zwischen Herkunft und Wahrnehmung k\u00fcnstlerisch\u001b[12D\u001b[K k\u00fcnstlerischer Qualit\u00e4t Please note that this is a machine-generated translation and may not be ful\u001b[3D\u001b[K fully acc - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thefamilyoffice.ch\/de\/analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Kettenanalyse zur Beziehung zwischen Herkunft und Wahrnehmung k\u00fcnstlerisch\u001b[12D\u001b[K k\u00fcnstlerischer Qualit\u00e4t Please note that this is a machine-generated translation and may not be ful\u001b[3D\u001b[K fully acc - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"twitter:description\" content=\"Kettenanalyse zur Beziehung zwischen Herkunft und Wahrnehmung k\u00fcnstlerisch\u001b[12D\u001b[K k\u00fcnstlerischer Qualit\u00e4t Please note that this is a machine-generated translation and may not be ful\u001b[3D\u001b[K fully acc - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"laurent\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de\\\/\"},\"author\":{\"name\":\"laurent\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\"},\"headline\":\"Kettenanalyse zur Beziehung zwischen Herkunft und Wahrnehmung k\u00fcnstlerisch\\u001b[12D\\u001b[K k\u00fcnstlerischer Qualit\u00e4t Please note that this is a machine-generated translation and may not be ful\\u001b[3D\\u001b[K fully acc\",\"datePublished\":\"2026-05-13T16:15:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de\\\/\"},\"wordCount\":36,\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de\\\/\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de\\\/\",\"name\":\"Kettenanalyse zur Beziehung zwischen Herkunft und Wahrnehmung k\u00fcnstlerisch\\u001b[12D\\u001b[K k\u00fcnstlerischer Qualit\u00e4t Please note that this is a machine-generated translation and may not be ful\\u001b[3D\\u001b[K fully acc - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/#website\"},\"datePublished\":\"2026-05-13T16:15:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\"},\"description\":\"Kettenanalyse zur Beziehung zwischen Herkunft und Wahrnehmung k\u00fcnstlerisch\\u001b[12D\\u001b[K k\u00fcnstlerischer Qualit\u00e4t Please note that this is a machine-generated translation and may not be ful\\u001b[3D\\u001b[K fully acc - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kettenanalyse zur Beziehung zwischen Herkunft und Wahrnehmung k\u00fcnstlerisch\\u001b[12D\\u001b[K k\u00fcnstlerischer Qualit\u00e4t Please note that this is a machine-generated translation and may not be ful\\u001b[3D\\u001b[K fully acc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/\",\"name\":\"The Family Office\",\"description\":\"The Family Office\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/de\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\",\"name\":\"laurent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"caption\":\"laurent\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kettenanalyse zur Beziehung zwischen Herkunft und Wahrnehmung k\u00fcnstlerisch\u001b[12D\u001b[K k\u00fcnstlerischer Qualit\u00e4t Please note that this is a machine-generated translation and may not be ful\u001b[3D\u001b[K fully acc - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","description":"Kettenanalyse zur Beziehung zwischen Herkunft und Wahrnehmung k\u00fcnstlerisch\u001b[12D\u001b[K k\u00fcnstlerischer Qualit\u00e4t Please note that this is a machine-generated translation and may not be ful\u001b[3D\u001b[K fully acc - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thefamilyoffice.ch\/de\/analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de\/","twitter_card":"summary_large_image","twitter_title":"Kettenanalyse zur Beziehung zwischen Herkunft und Wahrnehmung k\u00fcnstlerisch\u001b[12D\u001b[K k\u00fcnstlerischer Qualit\u00e4t Please note that this is a machine-generated translation and may not be ful\u001b[3D\u001b[K fully acc - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","twitter_description":"Kettenanalyse zur Beziehung zwischen Herkunft und Wahrnehmung k\u00fcnstlerisch\u001b[12D\u001b[K k\u00fcnstlerischer Qualit\u00e4t Please note that this is a machine-generated translation and may not be ful\u001b[3D\u001b[K fully acc - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","twitter_misc":{"Verfasst von":"laurent"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thefamilyoffice.ch\/de\/analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de\/#article","isPartOf":{"@id":"https:\/\/thefamilyoffice.ch\/de\/analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de\/"},"author":{"name":"laurent","@id":"https:\/\/thefamilyoffice.ch\/de\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee"},"headline":"Kettenanalyse zur Beziehung zwischen Herkunft und Wahrnehmung k\u00fcnstlerisch\u001b[12D\u001b[K k\u00fcnstlerischer Qualit\u00e4t Please note that this is a machine-generated translation and may not be ful\u001b[3D\u001b[K fully acc","datePublished":"2026-05-13T16:15:36+00:00","mainEntityOfPage":{"@id":"https:\/\/thefamilyoffice.ch\/de\/analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de\/"},"wordCount":36,"articleSection":["Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/thefamilyoffice.ch\/de\/analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de\/","url":"https:\/\/thefamilyoffice.ch\/de\/analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de\/","name":"Kettenanalyse zur Beziehung zwischen Herkunft und Wahrnehmung k\u00fcnstlerisch\u001b[12D\u001b[K k\u00fcnstlerischer Qualit\u00e4t Please note that this is a machine-generated translation and may not be ful\u001b[3D\u001b[K fully acc - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","isPartOf":{"@id":"https:\/\/thefamilyoffice.ch\/de\/#website"},"datePublished":"2026-05-13T16:15:36+00:00","author":{"@id":"https:\/\/thefamilyoffice.ch\/de\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee"},"description":"Kettenanalyse zur Beziehung zwischen Herkunft und Wahrnehmung k\u00fcnstlerisch\u001b[12D\u001b[K k\u00fcnstlerischer Qualit\u00e4t Please note that this is a machine-generated translation and may not be ful\u001b[3D\u001b[K fully acc - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","breadcrumb":{"@id":"https:\/\/thefamilyoffice.ch\/de\/analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thefamilyoffice.ch\/de\/analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/thefamilyoffice.ch\/de\/analyse-du-lien-entre-provenance-et-perception-de-la-qualite-artistique-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/thefamilyoffice.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Kettenanalyse zur Beziehung zwischen Herkunft und Wahrnehmung k\u00fcnstlerisch\u001b[12D\u001b[K k\u00fcnstlerischer Qualit\u00e4t Please note that this is a machine-generated translation and may not be ful\u001b[3D\u001b[K fully acc"}]},{"@type":"WebSite","@id":"https:\/\/thefamilyoffice.ch\/de\/#website","url":"https:\/\/thefamilyoffice.ch\/de\/","name":"The Family Office","description":"The Family Office","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thefamilyoffice.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/thefamilyoffice.ch\/de\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee","name":"laurent","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","caption":"laurent"}}]}},"_links":{"self":[{"href":"https:\/\/thefamilyoffice.ch\/de\/wp-json\/wp\/v2\/posts\/27741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thefamilyoffice.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thefamilyoffice.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/de\/wp-json\/wp\/v2\/comments?post=27741"}],"version-history":[{"count":0,"href":"https:\/\/thefamilyoffice.ch\/de\/wp-json\/wp\/v2\/posts\/27741\/revisions"}],"wp:attachment":[{"href":"https:\/\/thefamilyoffice.ch\/de\/wp-json\/wp\/v2\/media?parent=27741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/de\/wp-json\/wp\/v2\/categories?post=27741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/de\/wp-json\/wp\/v2\/tags?post=27741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}