{"id":22924,"date":"2024-07-26T00:59:55","date_gmt":"2024-07-25T22:59:55","guid":{"rendered":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721948393.png"},"modified":"2024-07-26T00:59:55","modified_gmt":"2024-07-25T22:59:55","slug":"1721948393-png","status":"inherit","type":"attachment","link":"https:\/\/thefamilyoffice.ch\/en\/strategies-for-saving-and-investing-for-big-families\/1721948393-png\/","title":{"rendered":"1721948393.png"},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-22924","attachment","type-attachment","status-inherit","hentry","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>1721948393.png - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse<\/title>\n<meta name=\"description\" content=\"1721948393.png - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thefamilyoffice.ch\/en\/strategies-for-saving-and-investing-for-big-families\/1721948393-png\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"1721948393.png - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"twitter:description\" content=\"1721948393.png - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721948393.png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/en\\\/strategies-for-saving-and-investing-for-big-families\\\/1721948393-png\\\/\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/en\\\/strategies-for-saving-and-investing-for-big-families\\\/1721948393-png\\\/\",\"name\":\"1721948393.png - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/en\\\/#website\"},\"datePublished\":\"2024-07-25T22:59:55+00:00\",\"description\":\"1721948393.png - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/en\\\/strategies-for-saving-and-investing-for-big-families\\\/1721948393-png\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thefamilyoffice.ch\\\/en\\\/strategies-for-saving-and-investing-for-big-families\\\/1721948393-png\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/en\\\/strategies-for-saving-and-investing-for-big-families\\\/1721948393-png\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/thefamilyoffice.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Strategies for Saving and Investing for Big Families\",\"item\":\"https:\\\/\\\/thefamilyoffice.ch\\\/en\\\/strategies-for-saving-and-investing-for-big-families\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1721948393.png\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/en\\\/\",\"name\":\"The Family Office\",\"description\":\"The Family Office\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thefamilyoffice.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"1721948393.png - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","description":"1721948393.png - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thefamilyoffice.ch\/en\/strategies-for-saving-and-investing-for-big-families\/1721948393-png\/","twitter_card":"summary_large_image","twitter_title":"1721948393.png - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","twitter_description":"1721948393.png - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","twitter_image":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721948393.png","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thefamilyoffice.ch\/en\/strategies-for-saving-and-investing-for-big-families\/1721948393-png\/","url":"https:\/\/thefamilyoffice.ch\/en\/strategies-for-saving-and-investing-for-big-families\/1721948393-png\/","name":"1721948393.png - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","isPartOf":{"@id":"https:\/\/thefamilyoffice.ch\/en\/#website"},"datePublished":"2024-07-25T22:59:55+00:00","description":"1721948393.png - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","breadcrumb":{"@id":"https:\/\/thefamilyoffice.ch\/en\/strategies-for-saving-and-investing-for-big-families\/1721948393-png\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thefamilyoffice.ch\/en\/strategies-for-saving-and-investing-for-big-families\/1721948393-png\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/thefamilyoffice.ch\/en\/strategies-for-saving-and-investing-for-big-families\/1721948393-png\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/thefamilyoffice.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Strategies for Saving and Investing for Big Families","item":"https:\/\/thefamilyoffice.ch\/en\/strategies-for-saving-and-investing-for-big-families\/"},{"@type":"ListItem","position":3,"name":"1721948393.png"}]},{"@type":"WebSite","@id":"https:\/\/thefamilyoffice.ch\/en\/#website","url":"https:\/\/thefamilyoffice.ch\/en\/","name":"The Family Office","description":"The Family Office","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thefamilyoffice.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721948393.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721948393-300x300.png\" class=\"attachment-medium size-medium\" alt=\"Finance\" srcset=\"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721948393-300x300.png 300w, https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721948393-150x150.png 150w, https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721948393-768x768.png 768w, https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721948393.png 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Finance","media_type":"image","mime_type":"image\/png","media_details":{"width":1024,"height":1024,"file":"2024\/07\/1721948393.png","filesize":1779710,"sizes":{"medium":{"file":"1721948393-300x300.png","width":300,"height":300,"filesize":153660,"mime_type":"image\/png","source_url":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721948393-300x300.png"},"thumbnail":{"file":"1721948393-150x150.png","width":150,"height":150,"filesize":45104,"mime_type":"image\/png","source_url":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721948393-150x150.png"},"medium_large":{"file":"1721948393-768x768.png","width":768,"height":768,"filesize":911845,"mime_type":"image\/png","source_url":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721948393-768x768.png"},"full":{"file":"1721948393.png","width":1024,"height":1024,"mime_type":"image\/png","source_url":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721948393.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":22923,"source_url":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721948393.png","_links":{"self":[{"href":"https:\/\/thefamilyoffice.ch\/en\/wp-json\/wp\/v2\/media\/22924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thefamilyoffice.ch\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/thefamilyoffice.ch\/en\/wp-json\/wp\/v2\/types\/attachment"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":22923,"href":"https:\/\/thefamilyoffice.ch\/en\/wp-json\/wp\/v2\/posts\/22923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}