{"id":28967,"date":"2026-05-13T19:57:14","date_gmt":"2026-05-13T17:57:14","guid":{"rendered":"https:\/\/thefamilyoffice.ch\/linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es\/"},"modified":"2026-05-13T19:57:14","modified_gmt":"2026-05-13T17:57:14","slug":"linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es","status":"publish","type":"post","link":"https:\/\/thefamilyoffice.ch\/es\/linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es\/","title":{"rendered":"Influencia geopol\u00edtica en la venta de obras de arte: lo que es necesario s\u001b[1D\u001b[K\nsaber\n\n(The Spanish translation is \u00abInfluencia geopol\u00edtica en la venta de obras de\u001b[2D\u001b[K\nde arte: lo que es necesario"},"content":{"rendered":"<p>Traduction en cours (Espa\u00f1ol)&#8230;<\/p>","protected":false},"excerpt":{"rendered":"<p>Traduction en cours (Espa\u00f1ol)&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-28967","post","type-post","status-publish","format-standard","hentry","category-sin-categorizar","category-38","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Influencia geopol\u00edtica en la venta de obras de arte: lo que es necesario s\u001b[1D\u001b[K saber (The Spanish translation is &quot;Influencia geopol\u00edtica en la venta de obras de\u001b[2D\u001b[K de arte: lo que es necesario - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse<\/title>\n<meta name=\"description\" content=\"Influencia geopol\u00edtica en la venta de obras de arte: lo que es necesario s\u001b[1D\u001b[K saber (The Spanish translation is &quot;Influencia geopol\u00edtica en la venta de obras de\u001b[2D\u001b[K de arte: lo que es necesario - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thefamilyoffice.ch\/es\/linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Influencia geopol\u00edtica en la venta de obras de arte: lo que es necesario s\u001b[1D\u001b[K saber (The Spanish translation is &quot;Influencia geopol\u00edtica en la venta de obras de\u001b[2D\u001b[K de arte: lo que es necesario - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"twitter:description\" content=\"Influencia geopol\u00edtica en la venta de obras de arte: lo que es necesario s\u001b[1D\u001b[K saber (The Spanish translation is &quot;Influencia geopol\u00edtica en la venta de obras de\u001b[2D\u001b[K de arte: lo que es necesario - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"laurent\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/es\\\/linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/es\\\/linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es\\\/\"},\"author\":{\"name\":\"laurent\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/es\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\"},\"headline\":\"Influencia geopol\u00edtica en la venta de obras de arte: lo que es necesario s\\u001b[1D\\u001b[K saber (The Spanish translation is \u00abInfluencia geopol\u00edtica en la venta de obras de\\u001b[2D\\u001b[K de arte: lo que es necesario\",\"datePublished\":\"2026-05-13T17:57:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/es\\\/linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es\\\/\"},\"wordCount\":44,\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/es\\\/linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es\\\/\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/es\\\/linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es\\\/\",\"name\":\"Influencia geopol\u00edtica en la venta de obras de arte: lo que es necesario s\\u001b[1D\\u001b[K saber (The Spanish translation is \\\"Influencia geopol\u00edtica en la venta de obras de\\u001b[2D\\u001b[K de arte: lo que es necesario - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/es\\\/#website\"},\"datePublished\":\"2026-05-13T17:57:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/es\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\"},\"description\":\"Influencia geopol\u00edtica en la venta de obras de arte: lo que es necesario s\\u001b[1D\\u001b[K saber (The Spanish translation is \\\"Influencia geopol\u00edtica en la venta de obras de\\u001b[2D\\u001b[K de arte: lo que es necesario - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/es\\\/linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thefamilyoffice.ch\\\/es\\\/linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/es\\\/linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/thefamilyoffice.ch\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Influencia geopol\u00edtica en la venta de obras de arte: lo que es necesario s\\u001b[1D\\u001b[K saber (The Spanish translation is \u00abInfluencia geopol\u00edtica en la venta de obras de\\u001b[2D\\u001b[K de arte: lo que es necesario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/es\\\/\",\"name\":\"The Family Office\",\"description\":\"The Family Office\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thefamilyoffice.ch\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/es\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\",\"name\":\"laurent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"caption\":\"laurent\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Influencia geopol\u00edtica en la venta de obras de arte: lo que es necesario s\u001b[1D\u001b[K saber (The Spanish translation is \"Influencia geopol\u00edtica en la venta de obras de\u001b[2D\u001b[K de arte: lo que es necesario - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","description":"Influencia geopol\u00edtica en la venta de obras de arte: lo que es necesario s\u001b[1D\u001b[K saber (The Spanish translation is \"Influencia geopol\u00edtica en la venta de obras de\u001b[2D\u001b[K de arte: lo que es necesario - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thefamilyoffice.ch\/es\/linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es\/","twitter_card":"summary_large_image","twitter_title":"Influencia geopol\u00edtica en la venta de obras de arte: lo que es necesario s\u001b[1D\u001b[K saber (The Spanish translation is \"Influencia geopol\u00edtica en la venta de obras de\u001b[2D\u001b[K de arte: lo que es necesario - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","twitter_description":"Influencia geopol\u00edtica en la venta de obras de arte: lo que es necesario s\u001b[1D\u001b[K saber (The Spanish translation is \"Influencia geopol\u00edtica en la venta de obras de\u001b[2D\u001b[K de arte: lo que es necesario - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","twitter_misc":{"Escrito por":"laurent"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thefamilyoffice.ch\/es\/linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es\/#article","isPartOf":{"@id":"https:\/\/thefamilyoffice.ch\/es\/linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es\/"},"author":{"name":"laurent","@id":"https:\/\/thefamilyoffice.ch\/es\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee"},"headline":"Influencia geopol\u00edtica en la venta de obras de arte: lo que es necesario s\u001b[1D\u001b[K saber (The Spanish translation is \u00abInfluencia geopol\u00edtica en la venta de obras de\u001b[2D\u001b[K de arte: lo que es necesario","datePublished":"2026-05-13T17:57:14+00:00","mainEntityOfPage":{"@id":"https:\/\/thefamilyoffice.ch\/es\/linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es\/"},"wordCount":44,"articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/thefamilyoffice.ch\/es\/linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es\/","url":"https:\/\/thefamilyoffice.ch\/es\/linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es\/","name":"Influencia geopol\u00edtica en la venta de obras de arte: lo que es necesario s\u001b[1D\u001b[K saber (The Spanish translation is \"Influencia geopol\u00edtica en la venta de obras de\u001b[2D\u001b[K de arte: lo que es necesario - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","isPartOf":{"@id":"https:\/\/thefamilyoffice.ch\/es\/#website"},"datePublished":"2026-05-13T17:57:14+00:00","author":{"@id":"https:\/\/thefamilyoffice.ch\/es\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee"},"description":"Influencia geopol\u00edtica en la venta de obras de arte: lo que es necesario s\u001b[1D\u001b[K saber (The Spanish translation is \"Influencia geopol\u00edtica en la venta de obras de\u001b[2D\u001b[K de arte: lo que es necesario - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","breadcrumb":{"@id":"https:\/\/thefamilyoffice.ch\/es\/linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thefamilyoffice.ch\/es\/linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/thefamilyoffice.ch\/es\/linfluence-geopolitique-sur-les-ventes-doeuvres-dart-ce-quil-faut-savoir-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/thefamilyoffice.ch\/es\/"},{"@type":"ListItem","position":2,"name":"Influencia geopol\u00edtica en la venta de obras de arte: lo que es necesario s\u001b[1D\u001b[K saber (The Spanish translation is \u00abInfluencia geopol\u00edtica en la venta de obras de\u001b[2D\u001b[K de arte: lo que es necesario"}]},{"@type":"WebSite","@id":"https:\/\/thefamilyoffice.ch\/es\/#website","url":"https:\/\/thefamilyoffice.ch\/es\/","name":"The Family Office","description":"The Family Office","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thefamilyoffice.ch\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/thefamilyoffice.ch\/es\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee","name":"laurent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","caption":"laurent"}}]}},"_links":{"self":[{"href":"https:\/\/thefamilyoffice.ch\/es\/wp-json\/wp\/v2\/posts\/28967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thefamilyoffice.ch\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thefamilyoffice.ch\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/es\/wp-json\/wp\/v2\/comments?post=28967"}],"version-history":[{"count":0,"href":"https:\/\/thefamilyoffice.ch\/es\/wp-json\/wp\/v2\/posts\/28967\/revisions"}],"wp:attachment":[{"href":"https:\/\/thefamilyoffice.ch\/es\/wp-json\/wp\/v2\/media?parent=28967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/es\/wp-json\/wp\/v2\/categories?post=28967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/es\/wp-json\/wp\/v2\/tags?post=28967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}