{"id":20802,"date":"2024-02-24T19:47:13","date_gmt":"2024-02-24T18:47:13","guid":{"rendered":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/02\/shelby-cobra-2140558_960_720.jpg"},"modified":"2024-02-24T19:47:13","modified_gmt":"2024-02-24T18:47:13","slug":"shelby-cobra-2140558_960_720-jpg","status":"inherit","type":"attachment","link":"https:\/\/thefamilyoffice.ch\/fr\/le-private-equity-quelles-opportunites-sur-les-marches-financiers\/shelby-cobra-2140558_960_720-jpg\/","title":{"rendered":"shelby-cobra-2140558_960_720.jpg"},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-20802","attachment","type-attachment","status-inherit","hentry","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>shelby-cobra-2140558_960_720.jpg - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse<\/title>\n<meta name=\"description\" content=\"shelby-cobra-2140558_960_720.jpg - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thefamilyoffice.ch\/fr\/le-private-equity-quelles-opportunites-sur-les-marches-financiers\/shelby-cobra-2140558_960_720-jpg\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"shelby-cobra-2140558_960_720.jpg - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"twitter:description\" content=\"shelby-cobra-2140558_960_720.jpg - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/02\/shelby-cobra-2140558_960_720.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/le-private-equity-quelles-opportunites-sur-les-marches-financiers\\\/shelby-cobra-2140558_960_720-jpg\\\/\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/le-private-equity-quelles-opportunites-sur-les-marches-financiers\\\/shelby-cobra-2140558_960_720-jpg\\\/\",\"name\":\"shelby-cobra-2140558_960_720.jpg - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#website\"},\"datePublished\":\"2024-02-24T18:47:13+00:00\",\"description\":\"shelby-cobra-2140558_960_720.jpg - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/le-private-equity-quelles-opportunites-sur-les-marches-financiers\\\/shelby-cobra-2140558_960_720-jpg\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/le-private-equity-quelles-opportunites-sur-les-marches-financiers\\\/shelby-cobra-2140558_960_720-jpg\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/le-private-equity-quelles-opportunites-sur-les-marches-financiers\\\/shelby-cobra-2140558_960_720-jpg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Private Equity : Quelles opportunit\u00e9s sur les march\u00e9s financiers ?\",\"item\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/le-private-equity-quelles-opportunites-sur-les-marches-financiers\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"shelby-cobra-2140558_960_720.jpg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/\",\"name\":\"The Family Office\",\"description\":\"The Family Office\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"shelby-cobra-2140558_960_720.jpg - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","description":"shelby-cobra-2140558_960_720.jpg - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thefamilyoffice.ch\/fr\/le-private-equity-quelles-opportunites-sur-les-marches-financiers\/shelby-cobra-2140558_960_720-jpg\/","twitter_card":"summary_large_image","twitter_title":"shelby-cobra-2140558_960_720.jpg - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","twitter_description":"shelby-cobra-2140558_960_720.jpg - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","twitter_image":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/02\/shelby-cobra-2140558_960_720.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thefamilyoffice.ch\/fr\/le-private-equity-quelles-opportunites-sur-les-marches-financiers\/shelby-cobra-2140558_960_720-jpg\/","url":"https:\/\/thefamilyoffice.ch\/fr\/le-private-equity-quelles-opportunites-sur-les-marches-financiers\/shelby-cobra-2140558_960_720-jpg\/","name":"shelby-cobra-2140558_960_720.jpg - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","isPartOf":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/#website"},"datePublished":"2024-02-24T18:47:13+00:00","description":"shelby-cobra-2140558_960_720.jpg - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","breadcrumb":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/le-private-equity-quelles-opportunites-sur-les-marches-financiers\/shelby-cobra-2140558_960_720-jpg\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thefamilyoffice.ch\/fr\/le-private-equity-quelles-opportunites-sur-les-marches-financiers\/shelby-cobra-2140558_960_720-jpg\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/thefamilyoffice.ch\/fr\/le-private-equity-quelles-opportunites-sur-les-marches-financiers\/shelby-cobra-2140558_960_720-jpg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/thefamilyoffice.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Le Private Equity : Quelles opportunit\u00e9s sur les march\u00e9s financiers ?","item":"https:\/\/thefamilyoffice.ch\/fr\/le-private-equity-quelles-opportunites-sur-les-marches-financiers\/"},{"@type":"ListItem","position":3,"name":"shelby-cobra-2140558_960_720.jpg"}]},{"@type":"WebSite","@id":"https:\/\/thefamilyoffice.ch\/fr\/#website","url":"https:\/\/thefamilyoffice.ch\/fr\/","name":"The Family Office","description":"The Family Office","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thefamilyoffice.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/02\/shelby-cobra-2140558_960_720.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/02\/shelby-cobra-2140558_960_720-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"Private Equity\" srcset=\"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/02\/shelby-cobra-2140558_960_720-300x200.jpg 300w, https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/02\/shelby-cobra-2140558_960_720-768x512.jpg 768w, https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/02\/shelby-cobra-2140558_960_720.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Private Equity","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":960,"height":640,"file":"2024\/02\/shelby-cobra-2140558_960_720.jpg","filesize":147226,"sizes":{"medium":{"file":"shelby-cobra-2140558_960_720-300x200.jpg","width":300,"height":200,"filesize":10619,"mime_type":"image\/jpeg","source_url":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/02\/shelby-cobra-2140558_960_720-300x200.jpg"},"thumbnail":{"file":"shelby-cobra-2140558_960_720-150x150.jpg","width":150,"height":150,"filesize":5128,"mime_type":"image\/jpeg","source_url":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/02\/shelby-cobra-2140558_960_720-150x150.jpg"},"medium_large":{"file":"shelby-cobra-2140558_960_720-768x512.jpg","width":768,"height":512,"filesize":55235,"mime_type":"image\/jpeg","source_url":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/02\/shelby-cobra-2140558_960_720-768x512.jpg"},"full":{"file":"shelby-cobra-2140558_960_720.jpg","width":960,"height":640,"mime_type":"image\/jpeg","source_url":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/02\/shelby-cobra-2140558_960_720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":20801,"source_url":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/02\/shelby-cobra-2140558_960_720.jpg","_links":{"self":[{"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/media\/20802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":20801,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/posts\/20801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}