{"id":22647,"date":"2024-07-09T23:40:17","date_gmt":"2024-07-09T21:40:17","guid":{"rendered":"https:\/\/thefamilyoffice.ch\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\/"},"modified":"2026-05-12T20:56:59","modified_gmt":"2026-05-12T18:56:59","slug":"les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial","status":"publish","type":"post","link":"https:\/\/thefamilyoffice.ch\/fr\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\/","title":{"rendered":"Les avantages des r\u00e9gimes de retraite dans la gestion de votre patrimoine fa&#8230;"},"content":{"rendered":"<p><strong>Les avantages des r\u00e9gimes de retraite dans la gestion de votre patrimoine familial<\/strong><\/p>\n<p><\/p>\n<p>La planification de la retraite est une composante essentielle de la gestion de votre patrimoine familial. Les r\u00e9gimes de retraite offrent une multitude d\u2019avantages qui vont bien au-del\u00e0 de la simple \u00e9pargne. Ils constituent non seulement un pilier de s\u00e9curit\u00e9 financi\u00e8re pour vos vieux jours, mais ils jouent \u00e9galement un r\u00f4le crucial dans la protection et la croissance de votre patrimoine familial. Voici un tour d\u2019horizon des principaux avantages des r\u00e9gimes de retraite.<\/p>\n<p><\/p>\n<p><strong>1. Stabilit\u00e9 Financi\u00e8re et S\u00e9curit\u00e9<\/strong><\/p>\n<p><\/p>\n<p>La principale force d\u2019un r\u00e9gime de retraite est la stabilit\u00e9 financi\u00e8re qu\u2019il procure. En cotisant r\u00e9guli\u00e8rement \u00e0 un plan de retraite, vous vous assurez un revenu r\u00e9gulier une fois que vous ne serez plus en activit\u00e9. Ce flux de revenus stable permet de maintenir votre niveau de vie et d\u2019assurer que vous pouvez faire face aux d\u00e9penses impr\u00e9vues, aux soins de sant\u00e9, et \u00e0 d\u2019autres besoins sans mettre en p\u00e9ril votre patrimoine familial.<\/p>\n<p><\/p>\n<p><strong>2. Avantages Fiscaux<\/strong><\/p>\n<p><\/p>\n<p>Les r\u00e9gimes de retraite offrent souvent des avantages fiscaux significatifs. En France, par exemple, les cotisations aux r\u00e9gimes d\u2019\u00e9pargne retraite sont souvent d\u00e9ductibles des imp\u00f4ts sur le revenu. Certaines entreprises offrent \u00e9galement des r\u00e9gimes de retraite avantageux qui permettent de b\u00e9n\u00e9ficier d\u2019exon\u00e9rations fiscales. Ces incitations fiscales vous permettent de maximiser votre \u00e9pargne tout en r\u00e9duisant votre charge fiscale, ce qui constitue une strat\u00e9gie intelligente pour la croissance de votre patrimoine.<\/p>\n<p><\/p>\n<p><strong>3. Effet de Capitalisation<\/strong><\/p>\n<p><\/p>\n<p>Gr\u00e2ce \u00e0 l\u2019effet de capitalisation, les sommes investies dans les r\u00e9gimes de retraite augmentent exponentiellement avec le temps. Les int\u00e9r\u00eats g\u00e9n\u00e9r\u00e9s par vos investissements sont eux-m\u00eames r\u00e9investis, cr\u00e9ant ainsi un effet boule de neige. Ce processus permet d&rsquo;accumuler un capital significatif au moment de la retraite, et donc de disposer de ressources financi\u00e8res substantielles pour profiter de cette nouvelle phase de vie.<\/p>\n<p><\/p>\n<p><strong>4. Diversification du Patrimoine<\/strong><\/p>\n<p><\/p>\n<p>Les r\u00e9gimes de retraite permettent \u00e9galement une diversification intelligente de vos actifs. La plupart des plans de retraite investissent dans une vari\u00e9t\u00e9 de classes d\u2019actifs, dont des actions, des obligations et des biens immobiliers. Cette diversification r\u00e9duit les risques en r\u00e9partissant les investissements sur plusieurs supports, ce qui peut stabiliser et potentiellement accro\u00eetre votre patrimoine sur le long terme.<\/p>\n<p><\/p>\n<p><strong>5. Protection en Cas de D\u00e9c\u00e8s<\/strong><\/p>\n<p><\/p>\n<p>Certains r\u00e9gimes de retraite offrent des prestations de survie, assurant ainsi une protection financi\u00e8re pour les membres de votre famille en cas de d\u00e9c\u00e8s. Vos b\u00e9n\u00e9ficiaires peuvent recevoir une rente ou un capital, ce qui peut les aider \u00e0 maintenir leur niveau de vie et \u00e0 assurer la continuit\u00e9 de vos projets familiaux.<\/p>\n<p><\/p>\n<p><strong>6. Pr\u00e9paration des Co\u00fbts des Soins de Longue Dur\u00e9e<\/strong><\/p>\n<p><\/p>\n<p>Avec l\u2019\u00e2ge, les co\u00fbts des soins de longue dur\u00e9e peuvent devenir une lourde charge financi\u00e8re. Disposer d\u2019un r\u00e9gime de retraite bien structur\u00e9 peut contribuer \u00e0 couvrir ces frais, \u00e9vitant ainsi que vos revenus de retraite et autres actifs ne soient \u00e9puis\u00e9s trop rapidement. Cela permet \u00e9galement de pr\u00e9server les actifs que vous pourriez vouloir transmettre \u00e0 vos h\u00e9ritiers.<\/p>\n<p><\/p>\n<p><strong>7. Tranquillit\u00e9 d\u2019Esprit<\/strong><\/p>\n<p><\/p>\n<p>Enfin, l\u2019un des avantages les plus pr\u00e9cieux est la tranquillit\u00e9 d\u2019esprit que procure une bonne planification de la retraite. Savoir que vous avez un plan solide et bien financ\u00e9 permet de profiter de la vie sans les soucis financiers constants. Cette s\u00e9r\u00e9nit\u00e9 est inestimable, non seulement pour vous, mais aussi pour les membres de votre famille.<\/p>\n<p><\/p>\n<p><strong>Conclusion<\/strong><\/p>\n<p><\/p>\n<p>L\u2019int\u00e9gration d\u2019un r\u00e9gime de retraite dans la gestion de votre patrimoine familial est une d\u00e9marche strat\u00e9gique qui pr\u00e9sente de multiples avantages. De la stabilit\u00e9 financi\u00e8re \u00e0 la r\u00e9duction des imp\u00f4ts, en passant par la diversification et la protection de vos proches, les r\u00e9gimes de retraite constituent un outil incontournable pour assurer une s\u00e9curit\u00e9 financi\u00e8re durable et optimiser la croissance de votre patrimoine familial. Ne n\u00e9gligez donc pas cette opportunit\u00e9 et faites des choix \u00e9clair\u00e9s pour pr\u00e9parer un avenir serein pour vous et votre famille.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les avantages des r\u00e9gimes de retraite dans la gestion de votre patrimoine familial La planification de la retraite est une composante essentielle de la gestion de votre patrimoine familial. Les r\u00e9gimes de retraite offrent une multitude d\u2019avantages qui vont bien au-del\u00e0 de la simple \u00e9pargne. Ils constituent non seulement un pilier de s\u00e9curit\u00e9 financi\u00e8re pour&hellip;<\/p>\n","protected":false},"author":1,"featured_media":22648,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[530],"tags":[],"class_list":["post-22647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-finance","category-530","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les avantages des r\u00e9gimes de retraite dans la gestion de votre patrimoine fa... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse<\/title>\n<meta name=\"description\" content=\"Les avantages des r\u00e9gimes de retraite dans la gestion de votre patrimoine fa... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thefamilyoffice.ch\/fr\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Les avantages des r\u00e9gimes de retraite dans la gestion de votre patrimoine fa... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"twitter:description\" content=\"Les avantages des r\u00e9gimes de retraite dans la gestion de votre patrimoine fa... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1720561231.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"laurent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\\\/\"},\"author\":{\"name\":\"laurent\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\"},\"headline\":\"Les avantages des r\u00e9gimes de retraite dans la gestion de votre patrimoine fa&#8230;\",\"datePublished\":\"2024-07-09T21:40:17+00:00\",\"dateModified\":\"2026-05-12T18:56:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\\\/\"},\"wordCount\":730,\"image\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thefamilyoffice.ch\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1720561231.png\",\"articleSection\":[\"Finance\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\\\/\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\\\/\",\"name\":\"Les avantages des r\u00e9gimes de retraite dans la gestion de votre patrimoine fa... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thefamilyoffice.ch\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1720561231.png\",\"datePublished\":\"2024-07-09T21:40:17+00:00\",\"dateModified\":\"2026-05-12T18:56:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\"},\"description\":\"Les avantages des r\u00e9gimes de retraite dans la gestion de votre patrimoine fa... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1720561231.png\",\"contentUrl\":\"https:\\\/\\\/thefamilyoffice.ch\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1720561231.png\",\"width\":1024,\"height\":1024,\"caption\":\"Finance\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les avantages des r\u00e9gimes de retraite dans la gestion de votre patrimoine fa&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/\",\"name\":\"The Family Office\",\"description\":\"The Family Office\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\",\"name\":\"laurent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"caption\":\"laurent\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les avantages des r\u00e9gimes de retraite dans la gestion de votre patrimoine fa... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","description":"Les avantages des r\u00e9gimes de retraite dans la gestion de votre patrimoine fa... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thefamilyoffice.ch\/fr\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\/","twitter_card":"summary_large_image","twitter_title":"Les avantages des r\u00e9gimes de retraite dans la gestion de votre patrimoine fa... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","twitter_description":"Les avantages des r\u00e9gimes de retraite dans la gestion de votre patrimoine fa... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","twitter_image":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1720561231.png","twitter_misc":{"\u00c9crit par":"laurent","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thefamilyoffice.ch\/fr\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\/#article","isPartOf":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\/"},"author":{"name":"laurent","@id":"https:\/\/thefamilyoffice.ch\/fr\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee"},"headline":"Les avantages des r\u00e9gimes de retraite dans la gestion de votre patrimoine fa&#8230;","datePublished":"2024-07-09T21:40:17+00:00","dateModified":"2026-05-12T18:56:59+00:00","mainEntityOfPage":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\/"},"wordCount":730,"image":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\/#primaryimage"},"thumbnailUrl":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1720561231.png","articleSection":["Finance"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/thefamilyoffice.ch\/fr\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\/","url":"https:\/\/thefamilyoffice.ch\/fr\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\/","name":"Les avantages des r\u00e9gimes de retraite dans la gestion de votre patrimoine fa... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","isPartOf":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\/#primaryimage"},"image":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\/#primaryimage"},"thumbnailUrl":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1720561231.png","datePublished":"2024-07-09T21:40:17+00:00","dateModified":"2026-05-12T18:56:59+00:00","author":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee"},"description":"Les avantages des r\u00e9gimes de retraite dans la gestion de votre patrimoine fa... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","breadcrumb":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thefamilyoffice.ch\/fr\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thefamilyoffice.ch\/fr\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\/#primaryimage","url":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1720561231.png","contentUrl":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1720561231.png","width":1024,"height":1024,"caption":"Finance"},{"@type":"BreadcrumbList","@id":"https:\/\/thefamilyoffice.ch\/fr\/les-avantages-des-regimes-de-retraite-dans-la-gestion-de-votre-patrimoine-familial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/thefamilyoffice.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Les avantages des r\u00e9gimes de retraite dans la gestion de votre patrimoine fa&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/thefamilyoffice.ch\/fr\/#website","url":"https:\/\/thefamilyoffice.ch\/fr\/","name":"The Family Office","description":"The Family Office","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thefamilyoffice.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/thefamilyoffice.ch\/fr\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee","name":"laurent","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","caption":"laurent"}}]}},"_links":{"self":[{"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/posts\/22647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/comments?post=22647"}],"version-history":[{"count":1,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/posts\/22647\/revisions"}],"predecessor-version":[{"id":26133,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/posts\/22647\/revisions\/26133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/media\/22648"}],"wp:attachment":[{"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/media?parent=22647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/categories?post=22647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/tags?post=22647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}