{"id":22740,"date":"2024-07-17T00:05:09","date_gmt":"2024-07-16T22:05:09","guid":{"rendered":"https:\/\/thefamilyoffice.ch\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\/"},"modified":"2024-07-17T00:05:09","modified_gmt":"2024-07-16T22:05:09","slug":"pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart","status":"publish","type":"post","link":"https:\/\/thefamilyoffice.ch\/fr\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\/","title":{"rendered":"Pourquoi la transparence est essentielle pour la croissance du march\u00e9 de l&rsquo;art"},"content":{"rendered":"<p><strong>Pourquoi la Transparence est Essentielle pour la Croissance du March\u00e9 de l&rsquo;Art<\/strong><\/p>\n<p><\/p>\n<p>Le march\u00e9 de l&rsquo;art a toujours \u00e9t\u00e9 envelopp\u00e9 d&rsquo;un certain myst\u00e8re et d&rsquo;une opacit\u00e9 qui intriguent autant qu&rsquo;ils inqui\u00e8tent les observateurs et les participants. Pourtant, dans un monde de plus en plus interconnect\u00e9 et informatis\u00e9, la transparence devient un imp\u00e9ratif. Voici pourquoi la transparence est non seulement b\u00e9n\u00e9fique mais essentielle pour la croissance du march\u00e9 de l&rsquo;art.<\/p>\n<p><\/p>\n<h3>Renforcement de la Confiance<\/h3>\n<p><\/p>\n<p>L&rsquo;un des piliers fondamentaux de tout march\u00e9 prosp\u00e8re est la confiance. Dans le march\u00e9 de l&rsquo;art, cette confiance est souvent mise \u00e0 l&rsquo;\u00e9preuve par des pratiques opaques, telles que l&rsquo;absence de d\u00e9voilement des prix de vente, la provenance floue des \u0153uvres, et les ventes priv\u00e9es secr\u00e8tes. La transparence, par contre, permet aux acheteurs et aux vendeurs de prendre des d\u00e9cisions inform\u00e9es, en sachant que les informations qu&rsquo;ils ont en leur possession sont correctes et v\u00e9rifiables.<\/p>\n<p><\/p>\n<h3>R\u00e9duction des Fraudes et de la Contrefa\u00e7on<\/h3>\n<p><\/p>\n<p>La contrefa\u00e7on et les fraudes artistiques sont des fl\u00e9aux majeurs qui sapent la stabilit\u00e9 et la cr\u00e9dibilit\u00e9 du march\u00e9 de l&rsquo;art. Un climat de transparence o\u00f9 les informations concernant la provenance, l&rsquo;authenticit\u00e9, et les transactions sont librement accessibles peut consid\u00e9rablement diminuer ces risques. Des bases de donn\u00e9es accessibles qui tracent le parcours complet d&rsquo;une \u0153uvre d&rsquo;art peuvent dissuader les tentatives de fraude et faciliter la restitution des \u0153uvres vol\u00e9es.<\/p>\n<p><\/p>\n<h3>\u00c9largissement de l&rsquo;Acc\u00e8s<\/h3>\n<p><\/p>\n<p>Le march\u00e9 de l&rsquo;art est souvent critiqu\u00e9 pour \u00eatre r\u00e9serv\u00e9 \u00e0 une \u00e9lite. La transparence peut toutefois d\u00e9mocratiser l&rsquo;acc\u00e8s \u00e0 ce march\u00e9. Lorsqu&rsquo;il y a une mise \u00e0 disposition libre des informations, m\u00eame les collectionneurs novices peuvent entrer sur le march\u00e9 avec une meilleure compr\u00e9hension des cotes, des tendances, et des historiques de prix. Cela peut \u00e9largir la base de participants, favorisant ainsi la croissance g\u00e9n\u00e9rale du secteur.<\/p>\n<p><\/p>\n<h3>Meilleure \u00c9valuation des \u0152uvres<\/h3>\n<p><\/p>\n<p>La transparence permet une \u00e9valuation plus objective des \u0153uvres d&rsquo;art, bas\u00e9e sur des donn\u00e9es concr\u00e8tes plut\u00f4t que sur des sp\u00e9culations. Les transactions publiques, les informations sur les ventes aux ench\u00e8res, et les historiques de propri\u00e9t\u00e9 peuvent contribuer \u00e0 une estimation plus juste des valeurs des \u0153uvres. Une \u00e9valuation pr\u00e9cise est b\u00e9n\u00e9fique \u00e0 la fois pour les acheteurs, qui veulent s&rsquo;assurer de ne pas surpayer, et pour les vendeurs, qui cherchent \u00e0 obtenir une juste valeur pour leurs actifs.<\/p>\n<p><\/p>\n<h3>Facilitation de l\u2019Investissement<\/h3>\n<p><\/p>\n<p>L&rsquo;art est de plus en plus consid\u00e9r\u00e9 comme une classe d&rsquo;actifs \u00e0 part enti\u00e8re. Pour attirer des investisseurs institutionnels et priv\u00e9s, le march\u00e9 de l&rsquo;art doit offrir les m\u00eames niveaux de transparence et de r\u00e9gulation que ceux rencontr\u00e9s dans les march\u00e9s financiers traditionnels. Les investisseurs sont plus susceptibles de placer leur argent dans des actifs dont les risques sont bien compris et les rendements potentiels bien \u00e9valu\u00e9s.<\/p>\n<p><\/p>\n<h3>Voyants de Croissance \u00c9conomique<\/h3>\n<p><\/p>\n<p>Un march\u00e9 de l&rsquo;art transparent peut refl\u00e9ter de mani\u00e8re plus pr\u00e9cise les tendances \u00e9conomiques globales et locales. La connaissance des dynamiques de prix et des pr\u00e9f\u00e9rences des acheteurs peut enrichir les analyses \u00e9conomiques et favoriser la croissance des industries li\u00e9es \u00e0 l&rsquo;art, telles que le tourisme culturel, les galeries, et les maisons de vente aux ench\u00e8res.<\/p>\n<p><\/p>\n<h3>Conclusion<\/h3>\n<p><\/p>\n<p>La transparence n&rsquo;est pas simplement un id\u00e9al \u00e9thique; elle est une n\u00e9cessit\u00e9 pratique pour la sant\u00e9 et la croissance du march\u00e9 de l&rsquo;art. En facilitant la confiance, en r\u00e9duisant les fraudes, en \u00e9largissant l&rsquo;acc\u00e8s et en permettant une \u00e9valuation plus pr\u00e9cise des \u0153uvres, la transparence pose les bases d&rsquo;un march\u00e9 plus robuste et dynamique. En fin de compte, un march\u00e9 de l&rsquo;art transparent n&rsquo;attire pas seulement plus de participants, il cr\u00e9e \u00e9galement un \u00e9cosyst\u00e8me plus durable et \u00e9quitable pour tous les acteurs impliqu\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pourquoi la Transparence est Essentielle pour la Croissance du March\u00e9 de l&rsquo;Art Le march\u00e9 de l&rsquo;art a toujours \u00e9t\u00e9 envelopp\u00e9 d&rsquo;un certain myst\u00e8re et d&rsquo;une opacit\u00e9 qui intriguent autant qu&rsquo;ils inqui\u00e8tent les observateurs et les participants. Pourtant, dans un monde de plus en plus interconnect\u00e9 et informatis\u00e9, la transparence devient un imp\u00e9ratif. Voici pourquoi la&hellip;<\/p>\n","protected":false},"author":1,"featured_media":22741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[477],"tags":[],"class_list":["post-22740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-art","category-477","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pourquoi la transparence est essentielle pour la croissance du march\u00e9 de l&#039;art - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse<\/title>\n<meta name=\"description\" content=\"Pourquoi la transparence est essentielle pour la croissance du march\u00e9 de l&#039;art - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thefamilyoffice.ch\/fr\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Pourquoi la transparence est essentielle pour la croissance du march\u00e9 de l&#039;art - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"twitter:description\" content=\"Pourquoi la transparence est essentielle pour la croissance du march\u00e9 de l&#039;art - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"laurent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\\\/\"},\"author\":{\"name\":\"laurent\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\"},\"headline\":\"Pourquoi la transparence est essentielle pour la croissance du march\u00e9 de l&rsquo;art\",\"datePublished\":\"2024-07-16T22:05:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\\\/\"},\"wordCount\":689,\"image\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thefamilyoffice.ch\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1721167522.png\",\"articleSection\":[\"Art\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\\\/\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\\\/\",\"name\":\"Pourquoi la transparence est essentielle pour la croissance du march\u00e9 de l'art - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thefamilyoffice.ch\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1721167522.png\",\"datePublished\":\"2024-07-16T22:05:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\"},\"description\":\"Pourquoi la transparence est essentielle pour la croissance du march\u00e9 de l'art - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1721167522.png\",\"contentUrl\":\"https:\\\/\\\/thefamilyoffice.ch\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1721167522.png\",\"width\":1024,\"height\":1024,\"caption\":\"Art\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pourquoi la transparence est essentielle pour la croissance du march\u00e9 de l&rsquo;art\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/\",\"name\":\"The Family Office\",\"description\":\"The Family Office\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\",\"name\":\"laurent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"caption\":\"laurent\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pourquoi la transparence est essentielle pour la croissance du march\u00e9 de l'art - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","description":"Pourquoi la transparence est essentielle pour la croissance du march\u00e9 de l'art - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thefamilyoffice.ch\/fr\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\/","twitter_card":"summary_large_image","twitter_title":"Pourquoi la transparence est essentielle pour la croissance du march\u00e9 de l'art - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","twitter_description":"Pourquoi la transparence est essentielle pour la croissance du march\u00e9 de l'art - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","twitter_misc":{"\u00c9crit par":"laurent","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thefamilyoffice.ch\/fr\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\/#article","isPartOf":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\/"},"author":{"name":"laurent","@id":"https:\/\/thefamilyoffice.ch\/fr\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee"},"headline":"Pourquoi la transparence est essentielle pour la croissance du march\u00e9 de l&rsquo;art","datePublished":"2024-07-16T22:05:09+00:00","mainEntityOfPage":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\/"},"wordCount":689,"image":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\/#primaryimage"},"thumbnailUrl":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721167522.png","articleSection":["Art"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/thefamilyoffice.ch\/fr\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\/","url":"https:\/\/thefamilyoffice.ch\/fr\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\/","name":"Pourquoi la transparence est essentielle pour la croissance du march\u00e9 de l'art - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","isPartOf":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\/#primaryimage"},"image":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\/#primaryimage"},"thumbnailUrl":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721167522.png","datePublished":"2024-07-16T22:05:09+00:00","author":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee"},"description":"Pourquoi la transparence est essentielle pour la croissance du march\u00e9 de l'art - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","breadcrumb":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thefamilyoffice.ch\/fr\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thefamilyoffice.ch\/fr\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\/#primaryimage","url":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721167522.png","contentUrl":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721167522.png","width":1024,"height":1024,"caption":"Art"},{"@type":"BreadcrumbList","@id":"https:\/\/thefamilyoffice.ch\/fr\/pourquoi-la-transparence-est-essentielle-pour-la-croissance-du-marche-de-lart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/thefamilyoffice.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Pourquoi la transparence est essentielle pour la croissance du march\u00e9 de l&rsquo;art"}]},{"@type":"WebSite","@id":"https:\/\/thefamilyoffice.ch\/fr\/#website","url":"https:\/\/thefamilyoffice.ch\/fr\/","name":"The Family Office","description":"The Family Office","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thefamilyoffice.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/thefamilyoffice.ch\/fr\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee","name":"laurent","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","caption":"laurent"}}]}},"_links":{"self":[{"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/posts\/22740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/comments?post=22740"}],"version-history":[{"count":0,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/posts\/22740\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/media\/22741"}],"wp:attachment":[{"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/media?parent=22740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/categories?post=22740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/tags?post=22740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}