{"id":22907,"date":"2024-07-25T00:15:29","date_gmt":"2024-07-24T22:15:29","guid":{"rendered":"https:\/\/thefamilyoffice.ch\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\/"},"modified":"2026-05-12T20:56:39","modified_gmt":"2026-05-12T18:56:39","slug":"succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage","status":"publish","type":"post","link":"https:\/\/thefamilyoffice.ch\/fr\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\/","title":{"rendered":"Succession et transmission du patrimoine: les erreurs \u00e0 \u00e9viter pour assurer&#8230;"},"content":{"rendered":"<h3>Succession et Transmission du Patrimoine: Les Erreurs \u00e0 \u00c9viter pour Assurer la P\u00e9rennit\u00e9 de Votre H\u00e9ritage<\/h3>\n<p><\/p>\n<p>La transmission du patrimoine est une \u00e9tape cruciale de la vie qui permet aux individus de pr\u00e9parer l&rsquo;avenir de leurs proches en assurant une continuit\u00e9 de leurs biens et de leurs ressources. Pourtant, nombreuses sont les personnes qui commettent des erreurs lors de ce processus, compromettant ainsi la p\u00e9rennit\u00e9 de leur h\u00e9ritage. Afin d&rsquo;\u00e9viter de telles d\u00e9convenues, voici un tour d&rsquo;horizon des erreurs \u00e0 \u00e9viter pour une succession sereine et ma\u00eetris\u00e9e.<\/p>\n<p><\/p>\n<h4>1. N\u00e9gliger la R\u00e9daction d\u2019un Testament Clair et Pr\u00e9cis<\/h4>\n<p><\/p>\n<p>R\u00e9diger un testament est une d\u00e9marche essentielle pour organiser la transmission de son patrimoine selon ses volont\u00e9s. Cependant, un document mal r\u00e9dig\u00e9 ou incompl\u00e9t pourrait causer des litiges familiaux et entra\u00eener une r\u00e9partition erron\u00e9e des biens. Pour \u00e9viter cette erreur, il est recommand\u00e9 de consulter un notaire ou un avocat sp\u00e9cialis\u00e9 en droit des successions afin de r\u00e9diger un testament clair, pr\u00e9cis et conforme \u00e0 la l\u00e9gislation en vigueur.<\/p>\n<p><\/p>\n<h4>2. Ignorer les R\u00e9percussions Fiscales<\/h4>\n<p><\/p>\n<p>La fiscalit\u00e9 successorale peut consid\u00e9rablement r\u00e9duire la valeur de l\u2019h\u00e9ritage transmis \u00e0 vos b\u00e9n\u00e9ficiaires. Par manque d&rsquo;information, nombreux sont ceux qui ne prennent pas en compte les droits de succession, les \u00e9ventuelles donations ant\u00e9rieures ou les abattements fiscaux. Pour optimiser la transmission de votre patrimoine, il est important de se renseigner sur les modalit\u00e9s fiscales et de planifier en cons\u00e9quence. Parmi les solutions, les donations anticip\u00e9es, les assurances-vie ou encore les pactes successoraux peuvent \u00eatre envisag\u00e9s pour minimiser l\u2019impact fiscal.<\/p>\n<p><\/p>\n<h4>3. Oublier d\u2019Actualiser sa Planification<\/h4>\n<p><\/p>\n<p>La vie est par essence impr\u00e9visible, avec ses nombreux changements tels que les mariages, les divorces, les naissances ou les d\u00e9c\u00e8s. Une planification successorale \u00e9tablie \u00e0 un moment pr\u00e9cis de la vie peut devenir obsol\u00e8te ou inappropri\u00e9e au fil du temps. Il est donc crucial de r\u00e9\u00e9valuer r\u00e9guli\u00e8rement sa strat\u00e9gie de transmission patrimoniale et de mettre \u00e0 jour les documents juridiques concern\u00e9s pour qu&rsquo;ils refl\u00e8tent fid\u00e8lement la situation actuelle et les volont\u00e9s du testateur.<\/p>\n<p><\/p>\n<h4>4. Ne Pas Pr\u00e9parer ses H\u00e9ritiers<\/h4>\n<p><\/p>\n<p>Pr\u00e9parer ses h\u00e9ritiers \u00e0 la gestion du patrimoine \u00e0 transmettre est tout aussi important que les d\u00e9marches l\u00e9gales. Nombre d&rsquo;h\u00e9ritiers peuvent se trouver d\u00e9munis face \u00e0 des biens dont ils ignorent la valeur ou les implications financi\u00e8res (entretien, gestion locative, etc.). Organiser des r\u00e9unions familiales pour expliquer clairement les d\u00e9cisions prises et former les h\u00e9ritiers \u00e0 la gestion des biens est une bonne pratique pour assurer une transition harmonieuse.<\/p>\n<p><\/p>\n<h4>5. Ne Pas Prot\u00e9ger ses Proches Vuln\u00e9rables<\/h4>\n<p><\/p>\n<p>Certaines situations familiales peuvent n\u00e9cessiter des dispositions sp\u00e9cifiques, notamment lorsqu&rsquo;il y a des b\u00e9n\u00e9ficiaires vuln\u00e9rables (enfants mineurs, personnes handicap\u00e9es, etc.). Il est pertinent de penser \u00e0 des outils comme les fiduciaries, les trusts ou encore la tutelle, qui permettent de prot\u00e9ger les int\u00e9r\u00eats de ces proches tout en facilitant la gestion de l\u2019h\u00e9ritage.<\/p>\n<p><\/p>\n<h4>6. Oublier les Assurances<\/h4>\n<p><\/p>\n<p>Les assurances-vie peuvent jouer un r\u00f4le pr\u00e9pond\u00e9rant dans la planification successorale. Elles offrent non seulement une opportunit\u00e9 de transmettre un capital \u00e0 un co\u00fbt fiscal avantageux mais \u00e9galement une solution pour couvrir les frais de succession ou prot\u00e9ger le conjoint survivant. Ne pas inclure cette composante dans la strat\u00e9gie de transmission peut constituer une perte d&rsquo;opportunit\u00e9s et de s\u00e9curit\u00e9 pour vos proches.<\/p>\n<p><\/p>\n<h4>Conclusion<\/h4>\n<p><\/p>\n<p>La transmission du patrimoine est une d\u00e9marche engageante qui n\u00e9cessite une r\u00e9flexion approfondie et une pr\u00e9paration rigoureuse. \u00c9viter les erreurs les plus courantes permet de s\u00e9curiser cet h\u00e9ritage et d&rsquo;assurer sa p\u00e9rennit\u00e9 pour les g\u00e9n\u00e9rations futures. Faire appel \u00e0 des professionnels du secteur et actualiser r\u00e9guli\u00e8rement votre planification sont des cl\u00e9s essentielles pour une transmission r\u00e9ussie et sereine. En adoptant ces bonnes pratiques, vous contribuerez \u00e0 la pr\u00e9servation de votre h\u00e9ritage familial et \u00e0 la tranquillit\u00e9 d&rsquo;esprit de vos proches.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Succession et Transmission du Patrimoine: Les Erreurs \u00e0 \u00c9viter pour Assurer la P\u00e9rennit\u00e9 de Votre H\u00e9ritage La transmission du patrimoine est une \u00e9tape cruciale de la vie qui permet aux individus de pr\u00e9parer l&rsquo;avenir de leurs proches en assurant une continuit\u00e9 de leurs biens et de leurs ressources. Pourtant, nombreuses sont les personnes qui commettent&hellip;<\/p>\n","protected":false},"author":1,"featured_media":22908,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[530],"tags":[],"class_list":["post-22907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-finance","category-530","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Succession et transmission du patrimoine: les erreurs \u00e0 \u00e9viter pour assurer... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse<\/title>\n<meta name=\"description\" content=\"Succession et transmission du patrimoine: les erreurs \u00e0 \u00e9viter pour assurer... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thefamilyoffice.ch\/fr\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Succession et transmission du patrimoine: les erreurs \u00e0 \u00e9viter pour assurer... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"twitter:description\" content=\"Succession et transmission du patrimoine: les erreurs \u00e0 \u00e9viter pour assurer... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721859343.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"laurent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\\\/\"},\"author\":{\"name\":\"laurent\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\"},\"headline\":\"Succession et transmission du patrimoine: les erreurs \u00e0 \u00e9viter pour assurer&#8230;\",\"datePublished\":\"2024-07-24T22:15:29+00:00\",\"dateModified\":\"2026-05-12T18:56:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\\\/\"},\"wordCount\":710,\"image\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thefamilyoffice.ch\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1721859343.png\",\"articleSection\":[\"Finance\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\\\/\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\\\/\",\"name\":\"Succession et transmission du patrimoine: les erreurs \u00e0 \u00e9viter pour assurer... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thefamilyoffice.ch\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1721859343.png\",\"datePublished\":\"2024-07-24T22:15:29+00:00\",\"dateModified\":\"2026-05-12T18:56:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\"},\"description\":\"Succession et transmission du patrimoine: les erreurs \u00e0 \u00e9viter pour assurer... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1721859343.png\",\"contentUrl\":\"https:\\\/\\\/thefamilyoffice.ch\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1721859343.png\",\"width\":1024,\"height\":1024,\"caption\":\"Finance\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Succession et transmission du patrimoine: les erreurs \u00e0 \u00e9viter pour assurer&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/\",\"name\":\"The Family Office\",\"description\":\"The Family Office\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\",\"name\":\"laurent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"caption\":\"laurent\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Succession et transmission du patrimoine: les erreurs \u00e0 \u00e9viter pour assurer... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","description":"Succession et transmission du patrimoine: les erreurs \u00e0 \u00e9viter pour assurer... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thefamilyoffice.ch\/fr\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\/","twitter_card":"summary_large_image","twitter_title":"Succession et transmission du patrimoine: les erreurs \u00e0 \u00e9viter pour assurer... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","twitter_description":"Succession et transmission du patrimoine: les erreurs \u00e0 \u00e9viter pour assurer... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","twitter_image":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721859343.png","twitter_misc":{"\u00c9crit par":"laurent","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thefamilyoffice.ch\/fr\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\/#article","isPartOf":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\/"},"author":{"name":"laurent","@id":"https:\/\/thefamilyoffice.ch\/fr\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee"},"headline":"Succession et transmission du patrimoine: les erreurs \u00e0 \u00e9viter pour assurer&#8230;","datePublished":"2024-07-24T22:15:29+00:00","dateModified":"2026-05-12T18:56:39+00:00","mainEntityOfPage":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\/"},"wordCount":710,"image":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\/#primaryimage"},"thumbnailUrl":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721859343.png","articleSection":["Finance"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/thefamilyoffice.ch\/fr\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\/","url":"https:\/\/thefamilyoffice.ch\/fr\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\/","name":"Succession et transmission du patrimoine: les erreurs \u00e0 \u00e9viter pour assurer... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","isPartOf":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\/#primaryimage"},"image":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\/#primaryimage"},"thumbnailUrl":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721859343.png","datePublished":"2024-07-24T22:15:29+00:00","dateModified":"2026-05-12T18:56:39+00:00","author":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee"},"description":"Succession et transmission du patrimoine: les erreurs \u00e0 \u00e9viter pour assurer... - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","breadcrumb":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thefamilyoffice.ch\/fr\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thefamilyoffice.ch\/fr\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\/#primaryimage","url":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721859343.png","contentUrl":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/07\/1721859343.png","width":1024,"height":1024,"caption":"Finance"},{"@type":"BreadcrumbList","@id":"https:\/\/thefamilyoffice.ch\/fr\/succession-et-transmission-du-patrimoine-les-erreurs-a-eviter-pour-assurer-la-perennite-de-votre-heritage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/thefamilyoffice.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Succession et transmission du patrimoine: les erreurs \u00e0 \u00e9viter pour assurer&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/thefamilyoffice.ch\/fr\/#website","url":"https:\/\/thefamilyoffice.ch\/fr\/","name":"The Family Office","description":"The Family Office","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thefamilyoffice.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/thefamilyoffice.ch\/fr\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee","name":"laurent","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","caption":"laurent"}}]}},"_links":{"self":[{"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/posts\/22907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/comments?post=22907"}],"version-history":[{"count":1,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/posts\/22907\/revisions"}],"predecessor-version":[{"id":26092,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/posts\/22907\/revisions\/26092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/media\/22908"}],"wp:attachment":[{"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/media?parent=22907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/categories?post=22907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/tags?post=22907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}