{"id":23957,"date":"2024-10-12T01:45:14","date_gmt":"2024-10-11T23:45:14","guid":{"rendered":"https:\/\/thefamilyoffice.ch\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\/"},"modified":"2024-10-12T01:45:14","modified_gmt":"2024-10-11T23:45:14","slug":"les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office","status":"publish","type":"post","link":"https:\/\/thefamilyoffice.ch\/fr\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\/","title":{"rendered":"Les cl\u00e9s d&rsquo;une retraite sereine gr\u00e2ce aux services d&rsquo;un family office"},"content":{"rendered":"<p><strong>Les Cl\u00e9s d&rsquo;une Retraite Sereine Gr\u00e2ce aux Services d&rsquo;un Family Office<\/strong><\/p>\n<p><\/p>\n<p>La retraite est une \u00e9tape de la vie qui suscite \u00e0 la fois excitation et appr\u00e9hension. Apr\u00e8s des d\u00e9cennies de travail, elle offre enfin l&rsquo;occasion de se consacrer \u00e0 ses passions, sa famille, ou encore \u00e0 des projets personnels laiss\u00e9s de c\u00f4t\u00e9 trop longtemps. Cependant, pour que cette p\u00e9riode soit v\u00e9ritablement sereine, une pr\u00e9paration minutieuse et une gestion financi\u00e8re prudente sont indispensables. C&rsquo;est l\u00e0 qu&rsquo;intervient le family office, un service encore m\u00e9connu du grand public mais qui gagne en popularit\u00e9 pour sa capacit\u00e9 \u00e0 transformer une retraite ordinaire en une retraite de r\u00eave.<\/p>\n<p><\/p>\n<p><strong>Qu&rsquo;est-ce qu&rsquo;un Family Office ?<\/strong><\/p>\n<p><\/p>\n<p>Le family office est une structure d\u00e9di\u00e9e \u00e0 la gestion patrimoniale priv\u00e9e des familles fortun\u00e9es. Initialement con\u00e7u pour les tr\u00e8s grandes fortunes, ce service s&rsquo;est d\u00e9mocratis\u00e9 et devient accessible \u00e0 des familles d\u00e9sireuses de b\u00e9n\u00e9ficier d&rsquo;une approche int\u00e9gr\u00e9e et personnalis\u00e9e de la gestion de leur patrimoine. Contrairement \u00e0 un simple conseiller financier, le family office offre un ensemble complet de services qui couvrent la planification financi\u00e8re, les investissements, la fiscalit\u00e9, la succession, la philanthrophie, et m\u00eame l&rsquo;\u00e9ducation financi\u00e8re des g\u00e9n\u00e9rations futures.<\/p>\n<p><\/p>\n<p><strong>Pourquoi Faire Appel \u00e0 un Family Office pour sa Retraite ?<\/strong><\/p>\n<p><\/p>\n<ol><\/p>\n<li>\n<p><strong>Planification Financi\u00e8re Personnalis\u00e9e<\/strong>: L&rsquo;un des principaux avantages de recourir \u00e0 un family office r\u00e9side dans la personnalisation de la strat\u00e9gie financi\u00e8re. Chaque individu ou famille a des objectifs, des besoins et des circonstances uniques, et un family office se charge de concevoir une feuille de route financi\u00e8re sur mesure. De cette mani\u00e8re, il est possible de s\u00e9curiser ses revenus, optimiser ses d\u00e9penses et garantir le financement des projets personnels ou familiaux.<\/p>\n<p>\n<\/li>\n<p><\/p>\n<li>\n<p><strong>Gestion Efficace des Investissements<\/strong>: La retraite ne signifie pas que l&rsquo;on se retire du monde des investissements ; bien au contraire. Maintenir un portefeuille d&rsquo;investissements diversifi\u00e9 et performant est crucial pour assurer une source de revenus stable. Les experts d&rsquo;un family office disposent des comp\u00e9tences n\u00e9cessaires pour analyser les march\u00e9s, anticiper les tendances et ajuster les placements en fonction des fluctuations \u00e9conomiques.<\/p>\n<p>\n<\/li>\n<p><\/p>\n<li>\n<p><strong>Optimisation Fiscale<\/strong>: La fiscalit\u00e9 peut repr\u00e9senter un d\u00e9fi majeur \u00e0 la retraite. Avec des r\u00e9glementations qui \u00e9voluent constamment, il est facile de se perdre et de commettre des erreurs co\u00fbteuses. Les fiscalistes d&rsquo;un family office ont pour mission d&rsquo;optimiser le cadre fiscal tout en assurant une conformit\u00e9 parfaite avec la l\u00e9gislation en vigueur. Cela se traduit par des \u00e9conomies significatives, permettant aux retrait\u00e9s de profiter pleinement de leur nouveau mode de vie.<\/p>\n<p>\n<\/li>\n<p><\/p>\n<li>\n<p><strong>Pr\u00e9paration de la Succession<\/strong>: Un autre aspect crucial de l&rsquo;accompagnement par un family office est la planification successorale. R\u00e9diger son testament, pr\u00e9voir des donations ou organiser une transmission patrimoniale \u00e0 moindre co\u00fbt fiscal sont autant de d\u00e9marches sensibles qui n\u00e9cessitent l&rsquo;expertise et la discr\u00e9tion d&rsquo;un family office. Ainsi, les retrait\u00e9s assurent la p\u00e9rennit\u00e9 de leur patrimoine et sa r\u00e9partition selon leurs souhaits.<\/p>\n<p>\n<\/li>\n<p><\/p>\n<li><strong>Soutien en Philanthropie<\/strong>: \u00c0 la retraite, nombreux sont ceux qui souhaitent s&rsquo;investir dans des projets philanthropiques. Le family office guide ses clients dans la conception et la gestion de leurs actions caritatives, garantissant un impact social ou environnemental maximal.<\/li>\n<p>\n<\/ol>\n<p><\/p>\n<p>En conclusion, le family office se pose comme un alli\u00e9 ind\u00e9fectible pour ceux qui aspirent \u00e0 une retraite sereine, en les soutenant \u00e0 chaque \u00e9tape pour optimiser leur patrimoine, atteindre leurs objectifs de vie et ainsi jouir pleinement de ce nouveau chapitre. Pour celles et ceux qui souhaitent aborder la retraite avec s\u00e9r\u00e9nit\u00e9 et confiance, recourir aux services d&rsquo;un family office n&rsquo;est pas seulement une option, c&rsquo;est une \u00e9vidence.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les Cl\u00e9s d&rsquo;une Retraite Sereine Gr\u00e2ce aux Services d&rsquo;un Family Office La retraite est une \u00e9tape de la vie qui suscite \u00e0 la fois excitation et appr\u00e9hension. Apr\u00e8s des d\u00e9cennies de travail, elle offre enfin l&rsquo;occasion de se consacrer \u00e0 ses passions, sa famille, ou encore \u00e0 des projets personnels laiss\u00e9s de c\u00f4t\u00e9 trop longtemps.&hellip;<\/p>\n","protected":false},"author":1,"featured_media":23958,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[530],"tags":[],"class_list":["post-23957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-finance","category-530","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les cl\u00e9s d&#039;une retraite sereine gr\u00e2ce aux services d&#039;un family office - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse<\/title>\n<meta name=\"description\" content=\"Les cl\u00e9s d&#039;une retraite sereine gr\u00e2ce aux services d&#039;un family office - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thefamilyoffice.ch\/fr\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Les cl\u00e9s d&#039;une retraite sereine gr\u00e2ce aux services d&#039;un family office - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"twitter:description\" content=\"Les cl\u00e9s d&#039;une retraite sereine gr\u00e2ce aux services d&#039;un family office - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"laurent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\\\/\"},\"author\":{\"name\":\"laurent\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\"},\"headline\":\"Les cl\u00e9s d&rsquo;une retraite sereine gr\u00e2ce aux services d&rsquo;un family office\",\"datePublished\":\"2024-10-11T23:45:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\\\/\"},\"wordCount\":659,\"image\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thefamilyoffice.ch\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1728690325.png\",\"articleSection\":[\"Finance\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\\\/\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\\\/\",\"name\":\"Les cl\u00e9s d'une retraite sereine gr\u00e2ce aux services d'un family office - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thefamilyoffice.ch\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1728690325.png\",\"datePublished\":\"2024-10-11T23:45:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\"},\"description\":\"Les cl\u00e9s d'une retraite sereine gr\u00e2ce aux services d'un family office - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1728690325.png\",\"contentUrl\":\"https:\\\/\\\/thefamilyoffice.ch\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1728690325.png\",\"width\":1024,\"height\":1024,\"caption\":\"Finance\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les cl\u00e9s d&rsquo;une retraite sereine gr\u00e2ce aux services d&rsquo;un family office\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/\",\"name\":\"The Family Office\",\"description\":\"The Family Office\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thefamilyoffice.ch\\\/fr\\\/#\\\/schema\\\/person\\\/cb845abedf2746f7aa952c3cd26158ee\",\"name\":\"laurent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g\",\"caption\":\"laurent\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les cl\u00e9s d'une retraite sereine gr\u00e2ce aux services d'un family office - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","description":"Les cl\u00e9s d'une retraite sereine gr\u00e2ce aux services d'un family office - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thefamilyoffice.ch\/fr\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\/","twitter_card":"summary_large_image","twitter_title":"Les cl\u00e9s d'une retraite sereine gr\u00e2ce aux services d'un family office - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","twitter_description":"Les cl\u00e9s d'une retraite sereine gr\u00e2ce aux services d'un family office - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","twitter_misc":{"\u00c9crit par":"laurent","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thefamilyoffice.ch\/fr\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\/#article","isPartOf":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\/"},"author":{"name":"laurent","@id":"https:\/\/thefamilyoffice.ch\/fr\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee"},"headline":"Les cl\u00e9s d&rsquo;une retraite sereine gr\u00e2ce aux services d&rsquo;un family office","datePublished":"2024-10-11T23:45:14+00:00","mainEntityOfPage":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\/"},"wordCount":659,"image":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\/#primaryimage"},"thumbnailUrl":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/10\/1728690325.png","articleSection":["Finance"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/thefamilyoffice.ch\/fr\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\/","url":"https:\/\/thefamilyoffice.ch\/fr\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\/","name":"Les cl\u00e9s d'une retraite sereine gr\u00e2ce aux services d'un family office - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","isPartOf":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\/#primaryimage"},"image":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\/#primaryimage"},"thumbnailUrl":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/10\/1728690325.png","datePublished":"2024-10-11T23:45:14+00:00","author":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee"},"description":"Les cl\u00e9s d'une retraite sereine gr\u00e2ce aux services d'un family office - The Family Office | Conseil en Investissement et Patrimoine Prive en Suisse","breadcrumb":{"@id":"https:\/\/thefamilyoffice.ch\/fr\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thefamilyoffice.ch\/fr\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thefamilyoffice.ch\/fr\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\/#primaryimage","url":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/10\/1728690325.png","contentUrl":"https:\/\/thefamilyoffice.ch\/wp-content\/uploads\/2024\/10\/1728690325.png","width":1024,"height":1024,"caption":"Finance"},{"@type":"BreadcrumbList","@id":"https:\/\/thefamilyoffice.ch\/fr\/les-cles-dune-retraite-sereine-grace-aux-services-dun-family-office\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/thefamilyoffice.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Les cl\u00e9s d&rsquo;une retraite sereine gr\u00e2ce aux services d&rsquo;un family office"}]},{"@type":"WebSite","@id":"https:\/\/thefamilyoffice.ch\/fr\/#website","url":"https:\/\/thefamilyoffice.ch\/fr\/","name":"The Family Office","description":"The Family Office","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thefamilyoffice.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/thefamilyoffice.ch\/fr\/#\/schema\/person\/cb845abedf2746f7aa952c3cd26158ee","name":"laurent","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90a816968b3ceb7024d182ddbdc52b13c98218943d5e597dae065c403c69d1d3?s=96&d=mm&r=g","caption":"laurent"}}]}},"_links":{"self":[{"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/posts\/23957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/comments?post=23957"}],"version-history":[{"count":0,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/posts\/23957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/media\/23958"}],"wp:attachment":[{"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/media?parent=23957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/categories?post=23957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thefamilyoffice.ch\/fr\/wp-json\/wp\/v2\/tags?post=23957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}